{"id":45,"date":"2026-02-27T12:38:55","date_gmt":"2026-02-27T11:38:55","guid":{"rendered":"https:\/\/sedanoc.rwdesarrollos2.es\/?post_type=servicio&#038;p=45"},"modified":"2026-07-14T13:59:35","modified_gmt":"2026-07-14T12:59:35","slug":"prevencion-de-riesgos-laborales","status":"publish","type":"servicio","link":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/","title":{"rendered":"Prevenci\u00f3n de Riesgos Laborales"},"featured_media":7756,"template":"","meta":{"_acf_changed":false},"class_list":["post-45","servicio","type-servicio","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prevenci\u00f3n de Riesgos Laborales | C Sedano<\/title>\n<meta name=\"description\" content=\"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prevenci\u00f3n de Riesgos Laborales | C Sedano\" \/>\n<meta property=\"og:description\" content=\"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/\" \/>\n<meta property=\"og:site_name\" content=\"C. Sedano &amp; Asociados\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T12:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csedano.com\/wp-content\/uploads\/2026\/03\/riesgos-sedano-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/\",\"url\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/\",\"name\":\"Prevenci\u00f3n de Riesgos Laborales | C Sedano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.csedano.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/riesgos-sedano-scaled.webp\",\"datePublished\":\"2026-02-27T11:38:55+00:00\",\"dateModified\":\"2026-07-14T12:59:35+00:00\",\"description\":\"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.csedano.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/riesgos-sedano-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.csedano.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/riesgos-sedano-scaled.webp\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/servicio\\\/prevencion-de-riesgos-laborales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prevenci\u00f3n de Riesgos Laborales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/\",\"name\":\"C. Sedano &amp; Asociados\",\"description\":\"Asesor\u00eda Laboral, Fiscal y Contable en Mallorca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prevenci\u00f3n de Riesgos Laborales | C Sedano","description":"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/","og_locale":"es_ES","og_type":"article","og_title":"Prevenci\u00f3n de Riesgos Laborales | C Sedano","og_description":"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.","og_url":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/","og_site_name":"C. Sedano &amp; Asociados","article_modified_time":"2026-07-14T12:59:35+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.csedano.com\/wp-content\/uploads\/2026\/03\/riesgos-sedano-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/","url":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/","name":"Prevenci\u00f3n de Riesgos Laborales | C Sedano","isPartOf":{"@id":"https:\/\/www.csedano.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/#primaryimage"},"image":{"@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csedano.com\/wp-content\/uploads\/2026\/03\/riesgos-sedano-scaled.webp","datePublished":"2026-02-27T11:38:55+00:00","dateModified":"2026-07-14T12:59:35+00:00","description":"Gesti\u00f3n y asesoramiento en prevenci\u00f3n de riesgos laborales en Mallorca. Expertos en seguridad, salud laboral, coordinaci\u00f3n de actividades y cumplimiento legal.","breadcrumb":{"@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/#primaryimage","url":"https:\/\/www.csedano.com\/wp-content\/uploads\/2026\/03\/riesgos-sedano-scaled.webp","contentUrl":"https:\/\/www.csedano.com\/wp-content\/uploads\/2026\/03\/riesgos-sedano-scaled.webp","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/www.csedano.com\/es\/servicio\/prevencion-de-riesgos-laborales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.csedano.com\/es\/"},{"@type":"ListItem","position":2,"name":"Prevenci\u00f3n de Riesgos Laborales"}]},{"@type":"WebSite","@id":"https:\/\/www.csedano.com\/es\/#website","url":"https:\/\/www.csedano.com\/es\/","name":"C. Sedano &amp; Asociados","description":"Asesor\u00eda Laboral, Fiscal y Contable en Mallorca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csedano.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/servicio\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/servicio"}],"about":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/types\/servicio"}],"version-history":[{"count":13,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/servicio\/45\/revisions"}],"predecessor-version":[{"id":11548,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/servicio\/45\/revisions\/11548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/media\/7756"}],"wp:attachment":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}