{"id":11172,"date":"2026-06-11T16:56:02","date_gmt":"2026-06-11T15:56:02","guid":{"rendered":"https:\/\/sedanoc.rwdesarrollos2.es\/?page_id=11172"},"modified":"2026-07-14T12:19:00","modified_gmt":"2026-07-14T11:19:00","slug":"politica-de-privacidad-videovigilancia","status":"publish","type":"page","link":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/","title":{"rendered":"Pol\u00edtica de privacidad videovigilancia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11172\" class=\"elementor elementor-11172\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17696dd e-con-full e-flex e-con e-parent\" data-id=\"17696dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6907cc6 e-con-full e-flex e-con e-child\" data-id=\"6907cc6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fdab5a elementor-widget elementor-widget-heading\" data-id=\"6fdab5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de privacidad videovigilancia<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eb5ff2 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"5eb5ff2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15f4d44 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"15f4d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"16\" viewBox=\"0 0 18 16\" fill=\"none\"><path d=\"M17.1278 6.75376L9.77998 0.359585C9.64449 0.244937 9.49337 0.156346 9.32661 0.093812C9.15985 0.0312767 8.98788 9.53674e-06 8.81069 9.53674e-06C8.63351 9.53674e-06 8.46154 0.0286713 8.29478 0.0859947C8.12802 0.143318 7.98211 0.234515 7.85704 0.359585L0.493578 6.75376C0.389353 6.84756 0.298157 6.957 0.219988 7.08207C0.14182 7.20714 0.0818907 7.34263 0.0402009 7.48854C0.00893353 7.63446 -0.00409454 7.78298 0.00111669 7.9341C0.00632792 8.08523 0.0349897 8.22854 0.0871019 8.36403C0.139214 8.49952 0.209566 8.6272 0.298157 8.74705C0.386747 8.86691 0.493578 8.96853 0.618647 9.05191C0.743717 9.13529 0.876603 9.20043 1.01731 9.24733C1.15801 9.29423 1.30132 9.31768 1.44723 9.31768H2.35399V14.5237C2.35399 14.7217 2.39046 14.9093 2.46342 15.0865C2.53638 15.2637 2.6406 15.42 2.77609 15.5555C2.91159 15.691 3.07053 15.7952 3.25292 15.8682C3.43532 15.9412 3.62031 15.9776 3.80792 15.9776H5.8872C6.08522 15.9776 6.27283 15.9412 6.45001 15.8682C6.62719 15.7952 6.78353 15.691 6.91902 15.5555C7.06493 15.42 7.17437 15.2637 7.24733 15.0865C7.32028 14.9093 7.35676 14.7217 7.35676 14.5237V12.4444C7.35676 12.3402 7.36719 12.2386 7.38803 12.1396C7.40888 12.0405 7.44014 11.9441 7.48183 11.8503C7.52352 11.7565 7.57303 11.6679 7.63035 11.5846C7.68768 11.5012 7.75803 11.423 7.84141 11.3501C7.91436 11.2875 7.99514 11.2302 8.08373 11.1781C8.17232 11.126 8.26352 11.0843 8.35732 11.053C8.46154 11.0218 8.56316 11.0009 8.66218 10.9905C8.76119 10.9801 8.86281 10.9801 8.96703 10.9905C9.15464 11.0218 9.32921 11.0817 9.49076 11.1703C9.65231 11.2589 9.79562 11.3761 9.92069 11.522C10.0353 11.6679 10.1239 11.8295 10.1865 12.0067C10.249 12.1839 10.2751 12.3663 10.2646 12.5539V14.5237C10.2646 14.7217 10.3037 14.9093 10.3819 15.0865C10.46 15.2637 10.5669 15.42 10.7024 15.5555C10.8379 15.691 10.9942 15.7952 11.1714 15.8682C11.3486 15.9412 11.5362 15.9776 11.7342 15.9776H13.8135C14.0115 15.9776 14.1991 15.9412 14.3763 15.8682C14.5535 15.7952 14.7098 15.691 14.8453 15.5555C14.9808 15.42 15.085 15.2637 15.158 15.0865C15.2309 14.9093 15.2674 14.7217 15.2674 14.5237V9.31768H16.1742C16.3201 9.31768 16.4634 9.29423 16.6041 9.24733C16.7448 9.20043 16.8777 9.13529 17.0027 9.05191C17.1278 8.96853 17.2346 8.86691 17.3232 8.74705C17.4118 8.6272 17.4822 8.49952 17.5343 8.36403C17.5864 8.22854 17.6177 8.08523 17.6281 7.9341C17.6385 7.78298 17.6229 7.63967 17.5812 7.50418C17.5499 7.35826 17.4952 7.22016 17.417 7.08988C17.3389 6.9596 17.2425 6.84756 17.1278 6.75376Z\" fill=\"#CF122D\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad1e80 elementor-widget elementor-widget-breadcrumbs\" data-id=\"bad1e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.csedano.com\/es\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff613b4 e-con-full e-flex e-con e-parent\" data-id=\"ff613b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e0fcf16 e-flex e-con-boxed e-con e-child\" data-id=\"e0fcf16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8a872 elementor-widget elementor-widget-text-editor\" data-id=\"1e8a872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00daltima modificaci\u00f3n: agosto de 2024<\/strong><\/p><p><strong>\u00daltima revisi\u00f3n: noviembre 2025<\/strong><\/p><p>\u00a0<\/p><p>Por favor lea detenidamente esta pol\u00edtica de privacidad. En ella encontrar\u00e1 informaci\u00f3n importante sobre el tratamiento de sus datos personales y los derechos que le reconoce la normativa vigente en la materia. Nos reservamos el derecho de actualizar nuestra pol\u00edtica de privacidad en cualquier momento con motivo de decisiones empresariales, as\u00ed como para cumplir con eventuales cambios legislativos o jurisprudenciales. Si tiene dudas o necesita cualquier aclaraci\u00f3n respecto a nuestra Pol\u00edtica de privacidad o a sus derechos, puede contactar con nosotros a trav\u00e9s de los canales que se indican m\u00e1s abajo.<\/p><p>\u00a0<\/p><h3><strong>\u00bfQui\u00e9n es el responsable del tratamiento de sus datos?<\/strong>\u00a0<\/h3><p><br \/>El responsable del tratamiento de sus datos es\u00a0<strong>C. SEDANO Y ASOCIADOS S.L.U.<\/strong>, con domicilio social en C\/Nuredduna 10, 2\u00baE, 07006, Palma, Illes Balears, y email: asesoria@csedano.com.<\/p><p>\u00a0<\/p><h3><strong>\u00bfPara qu\u00e9 trataremos sus datos y sobre qu\u00e9 base jur\u00eddica?<\/strong><\/h3><p><strong><br \/>Fines de seguridad:<\/strong>\u00a0tratamos los datos que se obtienen de las c\u00e1maras de videovigilancia instaladas con fines de videovigilancia y seguridad de las instalaciones.<\/p><p>Este tratamiento se basa en nuestro inter\u00e9s leg\u00edtimo en velar por la seguridad de las instalaciones. Para la ponderaci\u00f3n de este inter\u00e9s respecto a sus derechos y libertades se ha determinado que el tratamiento tiene un impacto limitado en la privacidad de los interesados, corresponde a expectativas razonables de los mismos y no plantea amenazas significativas.<\/p><p>\u00a0<\/p><h3><strong>\u00bfCu\u00e1nto tiempo conservaremos sus datos?<\/strong>\u00a0<\/h3><p><br \/>Los datos ser\u00e1n cancelados en el plazo m\u00e1ximo de un mes contado a partir del momento en que fueron captados, sin perjuicio de su conservaci\u00f3n durante los plazos previstos en las disposiciones legales aplicables, por ejemplo, para acreditar la comisi\u00f3n de actos que atenten contra la integridad de personas, bienes o instalaciones.<\/p><p>\u00a0<\/p><h3><strong>\u00bfA qui\u00e9n podemos comunicar sus datos?<\/strong><\/h3><p><br \/>No se comunicar\u00e1n sus datos a terceros, salvo a las autoridades competentes en caso de constatarse la comisi\u00f3n de actos que atenten contra la integridad de personas, bienes o instalaciones.<\/p><p>\u00a0<\/p><h3><strong>\u00bfCu\u00e1les son sus derechos?<\/strong>\u00a0<\/h3><p><br \/>Tiene derecho a obtener confirmaci\u00f3n de si estamos tratando o no sus datos personales y, en tal caso, acceder a los mismos. Puede igualmente pedir que sus datos sean rectificados cuando sean inexactos o a que se completen los datos que sean incompletos, as\u00ed como solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines para los que fueron recogidos. En determinadas circunstancias, podr\u00e1 solicitar la limitaci\u00f3n del tratamiento de sus datos. En tal caso, s\u00f3lo trataremos los datos afectados para la formulaci\u00f3n, el ejercicio o la defensa de reclamaciones o con miras a la protecci\u00f3n de los derechos de otras personas. En determinadas condiciones y por motivos relacionados con su situaci\u00f3n particular, podr\u00e1 igualmente oponerse al tratamiento de sus datos. En este caso dejaremos de tratar los datos, salvo por motivos leg\u00edtimos imperiosos que prevalezcan sobre sus intereses, derechos y libertades, o para la formulaci\u00f3n, el ejercicio o la defensa de reclamaciones. As\u00ed mismo y bajo ciertas condiciones podr\u00e1 solicitar la portabilidad de sus datos para que sean transmitidos a otro responsable del tratamiento. Para ejercer sus derechos deber\u00e1 remitirnos una solicitud acompa\u00f1ada de una copia de su documento nacional de identidad u otro documento v\u00e1lido que le identifique por correo postal o electr\u00f3nico a las direcciones indicadas en el apartado \u201c\u00bfQui\u00e9n es el responsable del tratamiento de sus datos?\u201d. Podr\u00e1 obtener m\u00e1s informaci\u00f3n sobre sus derechos y c\u00f3mo ejercerlos en la p\u00e1gina de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos en <a href=\"https:\/\/www.aepd.es\/\" target=\"_blank\" rel=\"noopener\">www.aepd.es<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00daltima modificaci\u00f3n: agosto de 2024 \u00daltima revisi\u00f3n: noviembre 2025 Por favor lea detenidamente esta pol\u00edtica de privacidad. En ella encontrar\u00e1 informaci\u00f3n importante sobre el tratamiento de sus datos personales y los derechos que le reconoce la normativa vigente en la materia. Nos reservamos el derecho de actualizar nuestra pol\u00edtica de privacidad en cualquier momento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11172","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u00daltima modificaci\u00f3n: agosto de 2024 \u00daltima revisi\u00f3n: noviembre 2025 Por favor lea detenidamente esta pol\u00edtica de privacidad. En ella encontrar\u00e1 informaci\u00f3n importante sobre el tratamiento de sus datos personales y los derechos que le reconoce la normativa vigente en la materia. Nos reservamos el derecho de actualizar nuestra pol\u00edtica de privacidad en cualquier momento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/\" \/>\n<meta property=\"og:site_name\" content=\"C. Sedano &amp; Asociados\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T11:19:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/politica-de-privacidad-videovigilancia\\\/\",\"url\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/politica-de-privacidad-videovigilancia\\\/\",\"name\":\"Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/#website\"},\"datePublished\":\"2026-06-11T15:56:02+00:00\",\"dateModified\":\"2026-07-14T11:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/politica-de-privacidad-videovigilancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csedano.com\\\/es\\\/politica-de-privacidad-videovigilancia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/politica-de-privacidad-videovigilancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad videovigilancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/\",\"name\":\"C. Sedano &amp; Asociados\",\"description\":\"Asesor\u00eda Laboral, Fiscal y Contable en Mallorca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csedano.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados","og_description":"\u00a0 \u00daltima modificaci\u00f3n: agosto de 2024 \u00daltima revisi\u00f3n: noviembre 2025 Por favor lea detenidamente esta pol\u00edtica de privacidad. En ella encontrar\u00e1 informaci\u00f3n importante sobre el tratamiento de sus datos personales y los derechos que le reconoce la normativa vigente en la materia. Nos reservamos el derecho de actualizar nuestra pol\u00edtica de privacidad en cualquier momento [&hellip;]","og_url":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/","og_site_name":"C. Sedano &amp; Asociados","article_modified_time":"2026-07-14T11:19:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/","url":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/","name":"Pol\u00edtica de privacidad videovigilancia - C. Sedano &amp; Asociados","isPartOf":{"@id":"https:\/\/www.csedano.com\/es\/#website"},"datePublished":"2026-06-11T15:56:02+00:00","dateModified":"2026-07-14T11:19:00+00:00","breadcrumb":{"@id":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.csedano.com\/es\/politica-de-privacidad-videovigilancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.csedano.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad videovigilancia"}]},{"@type":"WebSite","@id":"https:\/\/www.csedano.com\/es\/#website","url":"https:\/\/www.csedano.com\/es\/","name":"C. Sedano &amp; Asociados","description":"Asesor\u00eda Laboral, Fiscal y Contable en Mallorca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csedano.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/pages\/11172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/comments?post=11172"}],"version-history":[{"count":14,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/pages\/11172\/revisions"}],"predecessor-version":[{"id":12078,"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/pages\/11172\/revisions\/12078"}],"wp:attachment":[{"href":"https:\/\/www.csedano.com\/es\/wp-json\/wp\/v2\/media?parent=11172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}